{"id":315,"count":0,"description":"","link":"https:\/\/stagingkgd.com\/en\/haendler-region\/graubuenden-en\/","name":"Graub\u00fcnden","slug":"graubuenden-en","taxonomy":"haendler-region","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/stagingkgd.com\/en\/wp-json\/wp\/v2\/haendler-region\/315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stagingkgd.com\/en\/wp-json\/wp\/v2\/haendler-region"}],"about":[{"href":"https:\/\/stagingkgd.com\/en\/wp-json\/wp\/v2\/taxonomies\/haendler-region"}],"wp:post_type":[{"href":"https:\/\/stagingkgd.com\/en\/wp-json\/wp\/v2\/haendler?haendler-region=315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}